{"id":1382,"date":"2020-11-05T16:26:23","date_gmt":"2020-11-05T15:26:23","guid":{"rendered":"https:\/\/cifil.fr\/?p=1382"},"modified":"2020-11-05T16:26:24","modified_gmt":"2020-11-05T15:26:24","slug":"dispositif-pinel-le-loyer-est-encadre-et-les-revenus-du-locataire-plafonnes","status":"publish","type":"post","link":"https:\/\/cifil.fr\/index.php\/2020\/11\/05\/dispositif-pinel-le-loyer-est-encadre-et-les-revenus-du-locataire-plafonnes\/","title":{"rendered":"Dispositif Pinel: le loyer est encadr\u00e9 et les revenus du locataire plafonn\u00e9s"},"content":{"rendered":"\n<p style=\"text-align:center\"><\/p>\n\n\n\n<h2>LE DISPOSITIF PINEL permet de d\u00e9duire de vos imp\u00f4ts une partie du prix d&rsquo;acquisition d&rsquo;un logement s&rsquo;il est mis en location et respecte certains crit\u00e8res. <\/h2>\n\n\n\n<p>Le montant du loyer est plafonn\u00e9, tout comme les revenus des locataires.<\/p>\n\n\n\n<h3>Dispositif Pinel: les loyers sont bien encadr\u00e9s<\/h3>\n\n\n\n<p>Pour b\u00e9n\u00e9ficier de l&rsquo;avantage fiscal du Pinel, vous devez vous engager \u00e0 louer votre bien immobilier pendant une dur\u00e9e minimale de 6 \u00e0 12 ans.<\/p>\n\n\n\n<p>\u00c0 savoir que vous n&rsquo;\u00eates pas totalement libre de fixer le montant du loyer. En effet, celui-ci ne doit pas d\u00e9passer certains plafonds, hors charges. Ces plafonds varient en fonction de la surface du logement concern\u00e9 et de sa localisation. Ils sont r\u00e9vis\u00e9s chaque 1er janvier par d\u00e9cret.<\/p>\n\n\n\n<table class=\"wp-block-table\"><tbody><tr><td><strong>Localisation du logement<\/strong><\/td><td><strong>Plafond des loyers en 2020<\/strong><\/td><\/tr><tr><td>Zone A bis<\/td><td>17,43 \u20ac par m\u00e8tre carr\u00e9<\/td><\/tr><tr><td>Zone A<\/td><td>12,95 \u20ac par m\u00e8tre carr\u00e9<\/td><\/tr><tr><td>Zone B1<\/td><td>10,44 \u20ac par m\u00e8tre carr\u00e9<\/td><\/tr><\/tbody><\/table>\n\n\n\n<p>Un coefficient de correction a \u00e9t\u00e9 mis en place pour majorer le montant du loyer des petites surfaces et minorer celui des grandes. Le point d&rsquo;\u00e9quilibre (coefficient = 1) est atteint avec les logements de 63 m\u00e8tres carr\u00e9s. Il est calcul\u00e9 selon la formule suivante: 0,7 + 19 \/ surface totale. Ce coefficient est arrondi \u00e0 la deuxi\u00e8me d\u00e9cimale la plus proche et ne peut exc\u00e9der 1,2.<\/p>\n\n\n\n<p>Le calcul du plafond de loyer est fonction de deux indicateurs: la zone g\u00e9ographique et la surface pond\u00e9r\u00e9e. La surface pond\u00e9r\u00e9e correspond \u00e0 la somme de la surface habitable du logement et de la moiti\u00e9 des surfaces annexes, plafonn\u00e9es \u00e0 huit m\u00e8tres carr\u00e9s. La surface pond\u00e9r\u00e9e est \u00e9gale \u00e0: surface habitable du bien + surface des annexes \/ 2.<\/p>\n\n\n\n<p>Pour calculer le loyer maximum autoris\u00e9, il convient d&rsquo;appliquer la formule suivante: surface pond\u00e9r\u00e9e x plafond au m\u00e8tre carr\u00e9 de la zone g\u00e9ographique x coefficient de correction.<\/p>\n\n\n\n<h3>Les revenus des locataires sont plafonn\u00e9s<\/h3>\n\n\n\n<p>Pour pouvoir b\u00e9n\u00e9ficier de l&rsquo;avantage fiscal du dispositif Pinel, vousdevez louer votre bien \u00e0 des personnes dont les revenus ne d\u00e9passent pas un certain plafond lors de leur entr\u00e9e dans les lieux. Celui-ci varie en fonction de la composition du foyer de votre locataire et de la localisation de votre bien immobilier.<\/p>\n\n\n\n<p>Les plafonds de ressources pour 2020 sont consultables&nbsp;<a href=\"https:\/\/bofip.impots.gouv.fr\/bofip\/10130-PGP.html\/identifiant=BOI-BAREME-000017-20200207#I._Duflot_\/_Pinel_metropole_28\" rel=\"noreferrer noopener\" target=\"_blank\">ici<\/a>.<\/p>\n\n\n\n<h3>Important \u00e0 noter<\/h3>\n\n\n\n<p>Vous devez imp\u00e9rativement louer votre bien dans les 12 mois suivant la remise des clefs au propri\u00e9taire. Ce dernier doit en faire sa r\u00e9sidence principale. Si ces conditions ne sont pas respect\u00e9es, l&rsquo;avantage fiscal dispara\u00eet. Par ailleurs, le logement doit r\u00e9pondre \u00e0 certains crit\u00e8res (localisation, logement achet\u00e9 neuf ou ancien r\u00e9habilit\u00e9).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Articles \/ Sources : Boursorama Bnaque<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>CONTACTEZ-NOUS<\/strong> !<\/p>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-text-color has-col-ffffff-color has-background has-col-000000-background-color\" href=\"https:\/\/cifil.fr\/index.php\/contact\/\">J&rsquo;expose mon projet !<\/a><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" src=\"https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-1030x1022.png\" alt=\"\" class=\"wp-image-1311\" width=\"192\" height=\"191\" srcset=\"https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-1030x1022.png 1030w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-80x80.png 80w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-300x298.png 300w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-768x762.png 768w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-36x36.png 36w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-180x180.png 180w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-1500x1488.png 1500w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-705x699.png 705w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-120x120.png 120w, https:\/\/cifil.fr\/wp-content\/uploads\/2020\/10\/Logo-off-CIFIL-min-450x446.png 450w\" sizes=\"(max-width: 192px) 100vw, 192px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>LE DISPOSITIF PINEL permet de d\u00e9duire de vos imp\u00f4ts une partie du prix d&rsquo;acquisition d&rsquo;un logement s&rsquo;il est mis en location et respecte certains crit\u00e8res. Le montant du loyer est plafonn\u00e9, tout comme les revenus des locataires. Dispositif Pinel: les loyers sont bien encadr\u00e9s Pour b\u00e9n\u00e9ficier de l&rsquo;avantage fiscal du Pinel, vous devez vous engager [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/posts\/1382"}],"collection":[{"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1382"}],"version-history":[{"count":1,"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/posts\/1382\/revisions"}],"predecessor-version":[{"id":1384,"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/posts\/1382\/revisions\/1384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/media\/1383"}],"wp:attachment":[{"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cifil.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}